{"id":1381,"date":"2019-05-17T07:56:45","date_gmt":"2019-05-17T07:56:45","guid":{"rendered":"http:\/\/panespol.dev.trestristestigres.com\/?page_id=1381"},"modified":"2025-11-03T12:47:35","modified_gmt":"2025-11-03T11:47:35","slug":"panespol","status":"publish","type":"page","link":"https:\/\/panespol.com\/it\/","title":{"rendered":"Panespol"},"content":{"rendered":"\n<div class=\"alignnormal\"><div id=\"metaslider-id-6003\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-99-0 metaslider metaslider-flex metaslider-6003 ml-slider slider-home ms-theme-radix has-dots-nav\" role=\"region\" aria-label=\"Home IT\" data-width=\"1280\">\n    <div id=\"metaslider_container_6003\">\n        <div id=\"metaslider_6003\" class=\"flexslider\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-14631 ms-image \" aria-roledescription=\"slide\" data-date=\"2021-06-02 10:39:33\"><a href=\"https:\/\/panespol.com\/it\/dichiarazione-di-sostenibilita\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img decoding=\"async\" width=\"1475\" height=\"702\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/06\/Panespol-Sostenible-3.jpg\" class=\"slider-6003 slide-14631 msDefaultImage lazyload\" alt=\"Panespol Sostenible 3\" rel=\"\" title=\"Panespol Sostenible 3\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/06\/Panespol-Sostenible-3.jpg 1475w, https:\/\/panespol.com\/wp-content\/uploads\/2021\/06\/Panespol-Sostenible-3-300x143.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2021\/06\/Panespol-Sostenible-3-1024x487.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2021\/06\/Panespol-Sostenible-3-768x366.jpg 768w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1475px; --smush-placeholder-aspect-ratio: 1475\/702;\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><strong>Dichiarazione di sostenibilit\u00e0 e politica ambientale.<\/strong><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-13072 ms-image \" aria-roledescription=\"slide\" data-date=\"2020-09-30 11:04:25\"><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/novita\/quickjoin-system\/\" target=\"_self\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img decoding=\"async\" width=\"1920\" height=\"914\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol.jpg\" class=\"slider-6003 slide-13072 msDefaultImage lazyload\" alt=\"Banner QuickJoin System Panespol\" rel=\"\" title=\"Banner QuickJoin System Panespol\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol.jpg 1920w, https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol-300x143.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol-1024x487.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol-768x366.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol-1536x731.jpg 1536w, https:\/\/panespol.com\/wp-content\/uploads\/2020\/09\/Bannee-QuickJoin-System-Panespol-1568x746.jpg 1568w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1920px; --smush-placeholder-aspect-ratio: 1920\/914;\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><strong>Un nuovo sistema di installazione pi\u00f9 veloce, comodo e semplice.<\/strong><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6004 ms-image \" aria-roledescription=\"slide\" data-date=\"2019-10-25 09:42:25\"><a href=\"https:\/\/panespol.com\/it\/contatti\/\" target=\"_blank\" aria-label=\"View Slide Details\" class=\"metaslider_image_link\"><img decoding=\"async\" width=\"1281\" height=\"496\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4.jpg\" class=\"slider-6003 slide-6004 msDefaultImage lazyload\" alt=\"Slider 4\" rel=\"\" title=\"slider_4\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4.jpg 1281w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4-300x116.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4-768x297.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4-1024x396.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4-620x239.jpg 620w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_4-400x154.jpg 400w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/496;\" \/><\/a><div class=\"caption-wrap\"><div class=\"caption\"><strong>Progettiamo e produciamo soluzioni per trasformare facilmente il tuo spazio in tempo record. <\/strong><\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6005 ms-image \" aria-roledescription=\"slide\" data-date=\"2019-10-25 09:42:25\"><img decoding=\"async\" width=\"1281\" height=\"496\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3.jpg\" class=\"slider-6003 slide-6005 msDefaultImage lazyload\" alt=\"slider\" rel=\"\" title=\"slider_3\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3.jpg 1281w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3-300x116.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3-768x297.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3-1024x396.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3-620x239.jpg 620w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_3-400x154.jpg 400w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/496;\" \/><div class=\"caption-wrap\"><div class=\"caption\"><strong>Decoriamo <\/strong>spazi in tutto il mondo grazie alla nostra ampia variet\u00e0 di pannelli decorativi. Dal rivestimento che imita numerosi materiali come legno, ardesia, calcestruzzo o mattone, fino a texture ispirate alla natura. <\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6006 ms-image \" aria-roledescription=\"slide\" data-date=\"2019-10-25 09:42:25\"><img decoding=\"async\" width=\"1281\" height=\"496\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1.jpg\" class=\"slider-6003 slide-6006 msDefaultImage lazyload\" alt=\"slider 1\" rel=\"\" title=\"slider_1\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1.jpg 1281w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1-300x116.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1-768x297.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1-1024x396.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1-620x239.jpg 620w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_1-400x154.jpg 400w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/496;\" \/><div class=\"caption-wrap\"><div class=\"caption\"><strong>Ti aiutiamo a comunicare la tua personalit\u00e0 e a migliorare l'esperienza del consumatore<\/strong> con la nostra grande variet\u00e0 di pannelli. <\/div><\/div><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-6007 ms-image \" aria-roledescription=\"slide\" data-date=\"2019-10-25 09:42:25\"><img decoding=\"async\" width=\"1281\" height=\"496\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2.jpg\" class=\"slider-6003 slide-6007 msDefaultImage lazyload\" alt=\"\" rel=\"\" title=\"video-thumbnail\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2.jpg 1281w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2-300x116.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2-768x297.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2-1024x396.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2-620x239.jpg 620w, https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/slider_2-400x154.jpg 400w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/496;\" \/><div class=\"caption-wrap\"><div class=\"caption\"><span class=\"text-video-thumbnail\"><strong>Panespol<\/strong> in 3 minuti.<\/span><\/div><\/div><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading wow bounceInRight estilo-6\"><a href=\"https:\/\/panespol.com\/it\/surface-collections\/\">Surface Collections<\/a><\/h2>\n\n\n\n<p class=\"max-900 wow bounceInLeft before-tabs\">Il nostro catalogo di pannelli decorativi \u00e8 composto da oltre 300 articoli. Un&#8217;ampia variet\u00e0 di prodotti cui texture permettono di costruire spazi unici, dotandoli della personalit\u00e0 desiderata e tutto ci\u00f2 risparmiando tempo prezioso grazie alla loro facilit\u00e0 di montaggio.<\/p>\n\n\n\n<div class=\"wp-block-advgb-adv-tabs advgb-tabs-wrapper advgb-tab-horz-desktop advgb-tab-vert-tablet advgb-tab-stack-mobile advgb-tabs-7efee185-c788-411f-b6af-2ba0c00adfba\" data-tab-active=\"0\"><ul class=\"advgb-tabs-panel\" role=\"tablist\"><li class=\"advgb-tab advgb-tab-active\" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-0\" aria-controls=\"advgb-tab-panel-_b64d52-fd-0\" role=\"tab\" aria-selected=\"true\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Bricks<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-1\" aria-controls=\"advgb-tab-panel-_b64d52-fd-1\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Stones<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-2\" aria-controls=\"advgb-tab-panel-_b64d52-fd-2\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Slates<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-3\" aria-controls=\"advgb-tab-panel-_b64d52-fd-3\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Beton<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-4\" aria-controls=\"advgb-tab-panel-_b64d52-fd-4\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Wood<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-5\" aria-controls=\"advgb-tab-panel-_b64d52-fd-5\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Textures<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-6\" aria-controls=\"advgb-tab-panel-_b64d52-fd-6\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Tiles<\/span><\/button><\/li><li class=\"advgb-tab \" role=\"presentation\" style=\"background-color:#FFF;border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\"><button class=\"advgb-tab-button\" id=\"advgb-tab-_b64d52-fd-7\" aria-controls=\"advgb-tab-panel-_b64d52-fd-7\" role=\"tab\" aria-selected=\"false\" tabindex=\"0\" style=\"color:#111;background:none;border:none;width:100%;text-align:inherit;cursor:pointer;padding:8px 16px;font:inherit\"><span>Extras<\/span><\/button><\/li><\/ul><div class=\"advgb-tab-body-wrapper\" style=\"border-style:none;border-width:1px;border-color:#FFF;border-radius:10px\">\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- header-active\" id=\"advgb-tab-panel-_b64d52-fd-0\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-0\" tabindex=\"0\"><span>Bricks<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-0\" style=\"display:block\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/bricks_1-1-1024x736.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/736;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/bricks\/country-brick\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/PX-120-KFC-Country-Brick.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 427px; --smush-placeholder-aspect-ratio: 427\/427;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Country Brick<\/div>\n      <div>PX-120 KFC<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/bricks\/english-brick\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/PX-147-English-Brick.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 405px; --smush-placeholder-aspect-ratio: 405\/405;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">English Brick<\/div>\n      <div>PX-147 9016<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/bricks\/aldaia\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/P001-Aldaia-Panel1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 410px; --smush-placeholder-aspect-ratio: 410\/410;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Aldaia<\/div>\n      <div>PX-001<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/bricks\/caravista\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/PX-117-Caravista-Gris-Negro.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 415px; --smush-placeholder-aspect-ratio: 415\/415;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Caravista Gris Negro<\/div>\n      <div>PX-117<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/bricks\/urban-brick-2\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/P-084-Urban-Brick-3002-panel1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 394px; --smush-placeholder-aspect-ratio: 394\/394;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Urban Brick<\/div>\n      <div>PX-084 3002<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/bricks\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-1\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-1\" tabindex=\"0\"><span>Stones<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-1\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/stones_Mesa-de-trabajo-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/stones\/teruel\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/stones-02.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Teruel Gris<\/div>\n      <div>PX-054<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/stones\/navarra\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/stones-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Navarra Blanco<\/div>\n      <div>PX-053<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/stones\/marmol-travertino\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/stones-04.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">M\u00e1rmol Travertino<\/div>\n      <div>T-021<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/stones\/cuenca-restos\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/stones-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Cuenca<\/div>\n      <div>PX-016<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/stones\/cantabria\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/stones-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Cantabria Blanco<\/div>\n      <div>PX-034<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/stones\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-2\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-2\" tabindex=\"0\"><span>Slates<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-2\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/slates_Mesa-de-trabajo-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/slates\/pizarra\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/slates-02.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Pizarra<\/div>\n      <div>PX-006 9016<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/slates\/soria\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/slates-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Soria Arena<\/div>\n      <div>PX-018<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/slates\/laja-fina\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/slates-04.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Laja Fina Multicolor<\/div>\n      <div>PX-059<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/slates\/pirineos\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/slates-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Laja Pirineo Negro<\/div>\n      <div>PX-083<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/slates\/castilla\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/slates-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Laja Castilla<\/div>\n      <div>PX-087<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/slates\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-3\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-3\" tabindex=\"0\"><span>Beton<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-3\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/beton_Mesa-de-trabajo-1-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/beton\/bloque-hormigon\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/beton-02-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Bloque Hormig\u00f3n<\/div>\n      <div>PX-125 7020<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/beton\/beton-tablas\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/beton-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Beton Tablas<\/div>\n      <div>TX-022<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/beton\/smooth-beton\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/beton-04-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Smooth Beton Envejecido<\/div>\n      <div>TX-036<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/beton\/rough-beton\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/beton-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Rough Beton<\/div>\n      <div>TX-019<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/beton\/tiffany\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/beton-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Tiffany<\/div>\n      <div>PX-143 9016<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/beton\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-4\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-4\" tabindex=\"0\"><span>Wood<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-4\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/wood_Mesa-de-trabajo-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/wood\/bambu\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/10\/Detalle-PX-172-Bambu.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 740px; --smush-placeholder-aspect-ratio: 740\/556;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Bamb\u00fa<\/div>\n      <div>PX-172<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/wood\/madera-encofrada\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/wood-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Madera Encofrada<\/div>\n      <div>PX-133<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/wood\/arizona\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/wood-04.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Arizona Oro Viejo<\/div>\n      <div>PX-103<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/wood\/tabla-rustica-nogal\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/wood-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Tabla Madera<\/div>\n      <div>PX-049<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/wood\/nebraska\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/wood-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Nebraska Nogal Claro<\/div>\n      <div>PX-090<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/wood\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-6\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-6\" tabindex=\"0\"><span>Textures<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-6\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/textures_Mesa-de-trabajo-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/textures\/termoarcilla\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/textures-02.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Termoarcilla Envejecido<\/div>\n      <div>PX-124<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/textures\/sinkiang\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/textures-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Sinkiang Oro<\/div>\n      <div>PX-034<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/textures\/kashi\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/textures-04.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Kashi<\/div>\n      <div>T-025 9016<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/textures\/proyectado\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/textures-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Proyectado<\/div>\n      <div>PX-134 7030<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/textures\/kioto\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/textures-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Kioto<\/div>\n      <div>T-001<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/textures\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-7\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-7\" tabindex=\"0\"><span>Tiles<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-7\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/11\/PX-149-9003-Metro-1024x855.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/855;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/tiles\/classic-tile\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/tiles-02.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Classic Tile<\/div>\n      <div>PX-160 VRD<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/tiles\/rustic-tile\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/tiles-03.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Rustic Tile<\/div>\n      <div>PX-150 9010<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/tiles\/metro\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/tiles-04.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Metro<\/div>\n      <div>PX-149 9003<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/tiles\/metro\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/tiles-05.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Metro<\/div>\n      <div>PX-149 9005<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/tiles\/metro\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/tiles-06.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Metro<\/div>\n      <div>PX-149 5002<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n    \n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/tiles\/\">Mostra di pi\u00f9<\/a>\n   \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-tab advgb-tab-body-container\"><div class=\"advgb-tab-body-header advgb-tab-class- \" id=\"advgb-tab-panel-_b64d52-fd-8\" role=\"tabpanel\" aria-labelledby=\"advgb-tab-_b64d52-fd-8\" tabindex=\"0\"><span>Extras<\/span><\/div><div class=\"advgb-tab-_b64d52-fd advgb-tab-body\" aria-labelledby=\"advgb-tab-panel-_b64d52-fd-8\" style=\"display:none\">\n<div class=\"slider\">\n<div class=\"slider-col-left\">\n<img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2021\/03\/extras_Mesa-de-trabajo-1-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 635px; --smush-placeholder-aspect-ratio: 635\/485;\">\n<\/div>\n<div class=\"slider-col-right\">\n  <a href=\"\/surface-collections\/catalogo\/extras\/molduras-de-madera\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/extras-02-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Moldura Imitaci\u00f3n Madera<\/div>\n      <div>M-004<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/extras\/vigas-y-mensulas\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/extras-03-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/154;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">M\u00e9nsula Mediana<\/div>\n      <div>MV-002<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/extras\/molduras-de-piedra\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/extras-04-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Viga Grande<\/div>\n      <div>V-003<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/extras\/molduras-de-piedra\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/extras-05-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 312px; --smush-placeholder-aspect-ratio: 312\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Moldura Adorno<\/div>\n      <div>M-003<\/div>\n    <\/div>\n  <\/a>\n  <a href=\"\/surface-collections\/catalogo\/extras\/molduras-de-piedra\/\" class=\"slider-product\">\n    <div class=\"slider-product-img\">\n      <img decoding=\"async\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/06\/extras-06-1.png\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 313px; --smush-placeholder-aspect-ratio: 313\/155;\">\n    <\/div>\n    <div class=\"slider-product-text\">\n      <div class=\"bold\">Moldura Alcoy<\/div>\n      <div>M-006<\/div>\n    <\/div>\n  <\/a>\n  <div class=\"slider-product more-link\">\n      <a href=\"https:\/\/panespol.com\/surface-collections\/catalogo\/extras\/\">Mostra di pi\u00f9<\/a>  \n  <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"cta-montajes wow bounceInUp\">\n<div class=\"fl-grid flgrid--gutters\">\n            <div class=\"fl-grid-cell\">\n                <div class=\"cell-text\"> <span>Montaggi semplici, puliti e senza opere murarie<span><\/span><\/span><\/div>\n            <\/div>\n            <div class=\"fl-grid-cell\">\n                        <div class=\"fl-grid fl-grid--gutters\">\n            <div class=\"fl-grid-cell\">\n                <div class=\"cell-photo\"><img decoding=\"async\" data-src=\"\/wp-content\/uploads\/2019\/06\/1-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/374;\"><\/div>\n            <\/div>\n            <div class=\"fl-grid-cell\">\n                <div class=\"cell-photo\"><img decoding=\"async\" data-src=\"\/wp-content\/uploads\/2019\/06\/2-1.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/374;\"><\/div>\n            <\/div>\n           <div class=\"fl-grid-cell\">\n                <div class=\"cell-photo\"><img decoding=\"async\" data-src=\"\/wp-content\/uploads\/2019\/06\/5small.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/374;\"><\/div>\n            <\/div>\n        <\/div>\n            <\/div>\n        <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading estilo-6 wow bounceInRight invert\">Custom Made<\/h2>\n\n\n\n<p class=\"max-900 wow bounceInLeft invert\">Tu lo immagini e noi trasformiamo i tuoi disegni in qualsiasi rivestimento esclusivo o forme tridimensionali di qualsiasi dimensione, colore, texture o finitura. Innovative e intelligenti soluzioni decorative per le tue pareti e vetrine.<\/p>\n\n\n\n<div class=\"wp-block-cover hero-container wow fadeInUp\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-116 lazyload\" alt=\"\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2019\/05\/imagen-compo_Mesa-de-trabajo-1-copia-1.jpg\" data-object-fit=\"cover\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1281px; --smush-placeholder-aspect-ratio: 1281\/485;\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-large-font-size hero-title\"><code><a href=\"https:\/\/panespol.com\/it\/custom-made\/\">Qui<\/a><\/code><\/p>\n\n\n\n<p class=\"has-text-align-center hero-subtitle\"><a href=\"https:\/\/panespol.com\/it\/custom-made\/\">ti sveliamo come&#8230; <\/a><\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading estilo-6 wow bounceInRight\">Le ultime su Panespol<\/h2>\n\n\n<ul class=\"lcp_catlist wow slideInUp\" id=\"lcp_instance_0\"><li><h3><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/novita\/soluzioni-su-misura-per-progetti-impegnativi\/\">Soluzioni su misura per progetti impegnativi<\/a><\/h3><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/novita\/soluzioni-su-misura-per-progetti-impegnativi\/\" title=\"Soluzioni su misura per progetti impegnativi\"><img decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2024\/12\/8.jpg\" class=\"lcp_thumbnail wp-post-image lazyload\" alt=\"Soluzioni su misura per progetti impegnativi\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2024\/12\/8.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2024\/12\/8-300x200.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2024\/12\/8-768x512.jpg 768w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/a><p class=\"lcp_excerpt\">\nNoi di Panespol Systems sappiamo che l&#8217;interior design \u00e8 un campo in continua evoluzione, dove la creativit\u00e0 e l&#8217;innovazione giocano un ruolo fondamentale. Per questo motivo presentiamo la nostra gamma PANESPOL TEXTURES, una collezione pensata per i designer che vogliono sfidare i limiti ed esplorare nuove possibilit\u00e0.\n\n\nUna gamma che ispira\n\n\nPANESPOL TEXTURES non \u00e8 solo una ...<\/p><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/novita\/soluzioni-su-misura-per-progetti-impegnativi\/\">+<\/a><\/li><li><h3><a href=\"https:\/\/panespol.com\/it\/https\/panespolcom\/it\/https\/panespolcom\/it\/le-ultime-su-panespol\/tendenze\/ultime-tendenze-interior-design\/\">Panespol con le ultime tendenze dell\u2019interior design<\/a><\/h3><a href=\"https:\/\/panespol.com\/it\/https\/panespolcom\/it\/https\/panespolcom\/it\/le-ultime-su-panespol\/tendenze\/ultime-tendenze-interior-design\/\" title=\"Panespol con le ultime tendenze dell\u2019interior design\"><img decoding=\"async\" width=\"640\" height=\"426\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-1024x682.jpg\" class=\"lcp_thumbnail wp-post-image lazyload\" alt=\"Panespol con le ultime tendenze dell\u2019interior design\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-1024x682.jpg 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-300x200.jpg 300w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-768x512.jpg 768w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-1536x1024.jpg 1536w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023-1568x1045.jpg 1568w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Panespol-Casa-Decor-2023.jpg 1613w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/426;\" \/><\/a><p class=\"lcp_excerpt\">\nStoricamente e con frequenza, architetti, designer e interior designer hanno preferito la finitura reale all\u2019imitazione. Se il cliente poteva permetterselo, si suggeriva il legno naturale piuttosto che una copia. Ma l\u2019era della differenziazione \u00e8 tra noi, quindi lanciamo una domanda riflessiva:\u00a0\n\n\ncome possiamo distinguerci? In altre parole, come facciamo per lasciare la nostra impronta unica e ...<\/p><a href=\"https:\/\/panespol.com\/it\/https\/panespolcom\/it\/https\/panespolcom\/it\/le-ultime-su-panespol\/tendenze\/ultime-tendenze-interior-design\/\">+<\/a><\/li><li><h3><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/siamo-protagonisti\/panespol-e-il-marchio\/\">Panespol \u00e8 il marchio. Qualit\u00e0 garantita.<\/a><\/h3><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/siamo-protagonisti\/panespol-e-il-marchio\/\" title=\"Panespol \u00e8 il marchio. Qualit\u00e0 garantita.\"><img decoding=\"async\" width=\"640\" height=\"301\" data-src=\"https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-1024x482.png\" class=\"lcp_thumbnail wp-post-image lazyload\" alt=\"Panespol \u00e8 il marchio. Qualit\u00e0 garantita.\" data-srcset=\"https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-1024x482.png 1024w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-300x141.png 300w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-768x362.png 768w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-1536x724.png 1536w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol-1568x739.png 1568w, https:\/\/panespol.com\/wp-content\/uploads\/2023\/08\/Propiedad-Intelectual-Panespol.png 1872w\" data-sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/301;\" \/><\/a><p class=\"lcp_excerpt\">\n\nPanespol \u00e8 leader nel suo settore, anche se qualcuno potrebbe mettere in dubbio tale affermazione. Questo fa parte della libert\u00e0 di espressione e del legittimo gioco della concorrenza, ed \u00e8 soggetto al giudice supremo, cio\u00e8 il cliente.\n\n\nUna delle nostre strategie principali \u00e8 lo sviluppo di prodotti sia per i nostri clienti che per il nostro ...<\/p><a href=\"https:\/\/panespol.com\/it\/le-ultime-su-panespol\/siamo-protagonisti\/panespol-e-il-marchio\/\">+<\/a><\/li><\/ul>\n\n\n\n<div class=\"cta-columns wow bounceInUp\">\n<span class=\"cta-columns-title\">Vuoi che ti aiutiamo?<\/span>\n<span class=\"cta-columns-subtitle\">Contattaci e chiedi.<\/span>\n<a href=\"https:\/\/panespol.com\/it\/contatti\/\">Contactar<\/a>\n<\/div>\n<style class=\"advgb-styles-renderer\">.advgb-tabs-7efee185-c788-411f-b6af-2ba0c00adfba ul.advgb-tabs-panel li.advgb-tab.advgb-tab-active {background-color:#ffffff !important;color:#000000 !important;}#advgb-tabs-7efee185-c788-411f-b6af-2ba0c00adfba .advgb-tab-body-header.header-active, .advgb-tabs-7efee185-c788-411f-b6af-2ba0c00adfba .advgb-tab-body-header.header-active{background-color:#ffffff !important;color:#000000 !important;}<\/style>","protected":false},"excerpt":{"rendered":"<p>Surface Collections Il nostro catalogo di pannelli decorativi \u00e8 composto da oltre 300 articoli. Un&#8217;ampia variet\u00e0 di prodotti cui texture permettono di costruire spazi unici, dotandoli della personalit\u00e0 desiderata e tutto ci\u00f2 risparmiando tempo prezioso grazie alla loro facilit\u00e0 di montaggio. Montaggi semplici, puliti e senza opere murarie Custom Made Tu lo immagini e noi &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/panespol.com\/it\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Panespol&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-1381","page","type-page","status-publish","hentry","entry"],"acf":[],"rankMath":{"parentDomain":"panespol.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":true,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"panespol","permalinkFormat":"https:\/\/panespol.com\/it\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/panespol.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"Pannelli Decorativi - Panespol","description":"Il nostro catalogo di pannelli decorativi \u00e8 composto da oltre 300 articoli. Un\u2019ampia variet\u00e0 di prodotti cui texture permettono di costruire spazi unici, dotandoli della personalit\u00e0 desiderata e tutto ci\u00f2 risparmiando tempo prezioso grazie alla loro facilit\u00e0 di montaggio.","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"tttigres","titleTemplate":"%title% %sep% Paneles decorativos %sitename%","descriptionTemplate":"%title% %sep% %primary_category% %sep% %sitename%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/panespol.com\/it\/","objectID":1381,"objectType":"post","locale":"it","localeFull":"it_IT","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/panespol.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/panespol.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/panespol.com\/wp-content\/uploads\/2022\/11\/Ambiente-PX-211-Abeto-PANESPOL.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fpanespol.com%2Fit%2F&r=https%3A%2F%2Fpanespol.com%2Fit%2Fwp-json%2Fwp%2Fv2%2Fpages%2F1381%3Fnonce%3Da1e99c919f","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/panespol.com\/wp-content\/uploads\/2019\/11\/cropped-cropped-logo_short_Mesa-de-trabajo-1-1-32x32.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/panespol.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incredibile","sorprendente","meraviglioso","unico","bello","felicit\u00e0","brillante","affascinante","carismatico","scioccante","chiaro","completamente","riservato","fiducia","significativo","creativo","definitivamente","delizioso","dimostrare","sbrigati","determinato","degno","dinamico","impressionante","essenziale","ispiratore","innovativo","intenso","efficace","magico","magnifico","storico","importante","incredibile","indispensabile","indimenticabile","irresistibile","leggendario","luminoso","lusso","magico","magnifico","maestoso","memorabile","miracoloso","motivante","necessario","nuovo","ufficiale","perfetto","appassionato","persuasivo","fenomenale","piacere","popolare","potere","prestigioso","prodigioso","profondo","prospero","potente","qualit\u00e0","radiante","veloce","di successo","rivoluzionario","soddisfatto","sicurezza","sensazionale","sereno","lussuoso","splendido","sublime","sorprendente","talentuoso","terrificante","unico","valore","vibrante","vittorioso","vivace","veramente","zelante","autentico","avventuroso","spettacolare","esclusivo","garantito","straordinario","favoloso","affascinante","formidabile","geniale","grandioso","gratuito","abile","illimitato","impeccabile","infallibile","infinitamente","influente","ingegnoso","indimenticabile","insostituibile","leader","maestro","notevole","innovativo","pioniere","potente","riconosciuto","rivoluzionario","sorprendente","superiore","trionfante","ultra","coraggioso","prezioso","avanguardia","vigoroso","visionario","volont\u00e0","vitale","trionfo","glorioso","inarrestabile","ineguagliabile","intelligente","invincibile","libert\u00e0","orgoglio","pace","progresso","rinnovato","saggezza","soddisfazione","sicuro","serenit\u00e0","superamento","talento","trascendente","trasformativo","coraggio","vittoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Portada","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"coauthors":[],"author_meta":{"author_link":"https:\/\/panespol.com\/it\/author\/tttigres\/","display_name":"tttigres"},"relative_dates":{"created":"Pubblicato 7 years fa","modified":"Aggiornato 8 months fa"},"absolute_dates":{"created":"Pubblicato il May 17, 2019","modified":"Aggiornato il November 3, 2025"},"absolute_dates_time":{"created":"Pubblicato il May 17, 2019 7:56 am","modified":"Aggiornato il November 3, 2025 12:47 pm"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/pages\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":65,"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/pages\/1381\/revisions"}],"predecessor-version":[{"id":22998,"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/pages\/1381\/revisions\/22998"}],"wp:attachment":[{"href":"https:\/\/panespol.com\/it\/wp-json\/wp\/v2\/media?parent=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}